{"id":66920,"date":"2026-05-13T13:39:23","date_gmt":"2026-05-13T16:39:23","guid":{"rendered":"https:\/\/verdadeon.com.br\/portal\/?p=66920"},"modified":"2026-05-13T13:39:23","modified_gmt":"2026-05-13T16:39:23","slug":"homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca","status":"publish","type":"post","link":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/","title":{"rendered":"Homem de 27 anos pula muro de hospital e desaparece em Franca"},"content":{"rendered":"<h2>Lucas dos Anjos \u00e9 natural de Ipu\u00e3 e estava no hospital da Funda\u00e7\u00e3o Allan Kardec; colaborador registrou o desaparecimento<\/h2>\n<p style=\"text-align: right;\"><em><strong>Por Pedro Maia<\/strong><\/em><br \/>\n<em><strong>Editor-chefe<\/strong><\/em><\/p>\n<p>A Pol\u00edcia Civil de S\u00e3o Paulo, atrav\u00e9s do 3\u00b0 Distrito Policial de Franca, informa o desaparecimento de Lucas Henrique dos Anjos de Souza, de 27 anos, dado como desaparecido ap\u00f3s fugir do Hospital Allan Kardec (pertence \u00e0 funda\u00e7\u00e3o de nome hom\u00f4nimo) nesta ter\u00e7a-feira, 12.<\/p>\n<p>Um colaborador do hospital foi quem registrou o Boletim de Ocorr\u00eancia. Ele afirma que Lucas evadiu-se da institui\u00e7\u00e3o pulando o muro do setor masculino. Ele usava cal\u00e7a de abrigo, blusa de abrigo cinza e chinelo marrom.<\/p>\n<p>Henrique \u00e9 natural de Ipu\u00e3, a cerca de 76 quil\u00f4metros de Franca. Ap\u00f3s a fuga, n\u00e3o houve mais not\u00edcias de seu paradeiro. Caso algu\u00e9m o reconhe\u00e7a ou tenha informa\u00e7\u00f5es sobre onde ele possa estar, podem ser acionados:<\/p>\n<ul>\n<li>Pol\u00edcia Militar: Disque 190;<\/li>\n<li>Pol\u00edcia Civil: (16) 3722-2011;<\/li>\n<li>Hospital Allan Kardec: (16) 2103-3000 ou (16) 2103-3055;<\/li>\n<li>Maria Aparecida (M\u00e3e): (13) 97426-6758;<\/li>\n<li>Luis (Irm\u00e3o): (13) 98190-3013.<\/li>\n<\/ul>\n<div id=\"attachment_66922\" style=\"width: 2010px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-66922\" class=\"size-full wp-image-66922\" src=\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=1220%2C863&#038;ssl=1\" alt=\"\" width=\"1220\" height=\"863\" srcset=\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?w=2000&amp;ssl=1 2000w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=1024%2C724&amp;ssl=1 1024w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=1536%2C1086&amp;ssl=1 1536w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=207%2C146&amp;ssl=1 207w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=50%2C35&amp;ssl=1 50w, https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133745.639.jpg?resize=106%2C75&amp;ssl=1 106w\" sizes=\"auto, (max-width: 1220px) 100vw, 1220px\" \/><p id=\"caption-attachment-66922\" class=\"wp-caption-text\">Lucas Henrique dos Anjos de Souza, 27, desaparecido ap\u00f3s fugir do Hospital Allan Kardec, em Franca (\u00a9Divulga\u00e7\u00e3o\/PC)<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lucas dos Anjos \u00e9 natural de Ipu\u00e3 e estava no hospital da Funda\u00e7\u00e3o Allan Kardec; colaborador registrou o desaparecimento Por Pedro Maia Editor-chefe A Pol\u00edcia Civil<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":10,"featured_media":66921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[28,81],"tags":[],"class_list":["post-66920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-manchete"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn\" \/>\n<meta property=\"og:description\" content=\"Lucas dos Anjos \u00e9 natural de Ipu\u00e3 e estava no hospital da Funda\u00e7\u00e3o Allan Kardec; colaborador registrou o desaparecimento Por Pedro Maia Editor-chefe A Pol\u00edcia Civil [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/\" \/>\n<meta property=\"og:site_name\" content=\"VerdadeOn\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T16:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacao VerdadeOn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacao VerdadeOn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/\",\"url\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/\",\"name\":\"Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn\",\"isPartOf\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1\",\"datePublished\":\"2026-05-13T16:39:23+00:00\",\"author\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f\"},\"breadcrumb\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1\",\"width\":2000,\"height\":1414,\"caption\":\"Lucas Henrique dos Anjos de Souza, 27, desaparecido ap\u00f3s fugir do Hospital Allan Kardec, em Franca (\u00a9Divulga\u00e7\u00e3o\/PC)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/verdadeon.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homem de 27 anos pula muro de hospital e desaparece em Franca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#website\",\"url\":\"https:\/\/verdadeon.com.br\/portal\/\",\"name\":\"VerdadeOn\",\"description\":\"Not\u00edcias di\u00e1rias sobre Franca, Regi\u00e3o, Esporte, Cultura, Cotidiano, Colunas. Cobertura nos principais eventos da cidade \u00e9 aqui - Verdadeon Franca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/verdadeon.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f\",\"name\":\"Redacao VerdadeOn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g\",\"caption\":\"Redacao VerdadeOn\"},\"url\":\"https:\/\/verdadeon.com.br\/portal\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/","og_locale":"pt_BR","og_type":"article","og_title":"Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn","og_description":"Lucas dos Anjos \u00e9 natural de Ipu\u00e3 e estava no hospital da Funda\u00e7\u00e3o Allan Kardec; colaborador registrou o desaparecimento Por Pedro Maia Editor-chefe A Pol\u00edcia Civil [\u2026]","og_url":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/","og_site_name":"VerdadeOn","article_published_time":"2026-05-13T16:39:23+00:00","og_image":[{"width":2000,"height":1414,"url":"https:\/\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg","type":"image\/jpeg"}],"author":"Redacao VerdadeOn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacao VerdadeOn","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/","url":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/","name":"Homem de 27 anos pula muro de hospital e desaparece em Franca - VerdadeOn","isPartOf":{"@id":"https:\/\/verdadeon.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage"},"image":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1","datePublished":"2026-05-13T16:39:23+00:00","author":{"@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f"},"breadcrumb":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#primaryimage","url":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1","contentUrl":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1","width":2000,"height":1414,"caption":"Lucas Henrique dos Anjos de Souza, 27, desaparecido ap\u00f3s fugir do Hospital Allan Kardec, em Franca (\u00a9Divulga\u00e7\u00e3o\/PC)"},{"@type":"BreadcrumbList","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/13\/homem-de-27-anos-pula-muro-de-hospital-e-desaparece-em-franca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/verdadeon.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Homem de 27 anos pula muro de hospital e desaparece em Franca"}]},{"@type":"WebSite","@id":"https:\/\/verdadeon.com.br\/portal\/#website","url":"https:\/\/verdadeon.com.br\/portal\/","name":"VerdadeOn","description":"Not\u00edcias di\u00e1rias sobre Franca, Regi\u00e3o, Esporte, Cultura, Cotidiano, Colunas. Cobertura nos principais eventos da cidade \u00e9 aqui - Verdadeon Franca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/verdadeon.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f","name":"Redacao VerdadeOn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g","caption":"Redacao VerdadeOn"},"url":"https:\/\/verdadeon.com.br\/portal\/author\/redacao\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/05\/Documento-a4-placa-empurre-puxe-para-abrir-verde-2026-05-13T133645.998.jpg?fit=2000%2C1414&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/comments?post=66920"}],"version-history":[{"count":1,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66920\/revisions"}],"predecessor-version":[{"id":66923,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66920\/revisions\/66923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/media\/66921"}],"wp:attachment":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/media?parent=66920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/categories?post=66920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/tags?post=66920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}