{"id":66847,"date":"2026-05-11T17:02:17","date_gmt":"2026-05-11T20:02:17","guid":{"rendered":"https:\/\/verdadeon.com.br\/portal\/?p=66847"},"modified":"2026-05-11T17:02:17","modified_gmt":"2026-05-11T20:02:17","slug":"como-se-nao-houvesse-amanha","status":"publish","type":"post","link":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/","title":{"rendered":"Como se n\u00e3o houvesse amanh\u00e3"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><em>*Rafael Cervone<\/em><\/strong><\/p>\n<p>\u00c9 lament\u00e1vel constatar que n\u00f3s, brasileiros, estamos inclu\u00eddos entre os 3,4 bilh\u00f5es de pessoas que vivem em na\u00e7\u00f5es nas quais o dinheiro destinado ao pagamento dos juros da d\u00edvida p\u00fablica supera o montante referente \u00e0 sa\u00fade e \u00e0 educa\u00e7\u00e3o. Esses pa\u00edses s\u00e3o apontados no Relat\u00f3rio 2026 sobre Financiamento dos Objetivos de Desenvolvimento Sustent\u00e1vel (ODS), que acaba de ser publicado pela ONU.<\/p>\n<p>Visando dimensionar o impacto negativo dessa distor\u00e7\u00e3o para a nossa economia e a nossa popula\u00e7\u00e3o, fa\u00e7o aqui uma r\u00e1pida an\u00e1lise de alguns n\u00fameros oficiais do Brasil, que ultrapassou a marca de um trilh\u00e3o de reais em juros nominais, para o servi\u00e7o da d\u00edvida, acumulados em 12 meses at\u00e9 fevereiro de 2026, o equivalente a cerca de 8% do PIB. Trata-se de um dos maiores pesos relativos do mundo. A perversa equa\u00e7\u00e3o \u00e9 impulsionada pela Selic persistentemente elevada, que se manteve num patamar exagerado (14,50% ao ano) na reuni\u00e3o do Copom realizada na \u00faltima semana de abril. Isso, sem falar do spread igualmente alto.<\/p>\n<p>Em contraste, o or\u00e7amento federal da sa\u00fade para 2026 \u00e9 de R$ 271,3 bilh\u00f5es e o da educa\u00e7\u00e3o e cultura, R$ 233,4 bilh\u00f5es, perfazendo R$ 504,7 bilh\u00f5es. A compara\u00e7\u00e3o \u00e9 absurda e inc\u00f4moda, pois pagamos duas vezes mais para remunerar credores com juros imorais do que o total de tudo o que despendemos para cuidar da vida humana e formar as novas gera\u00e7\u00f5es. O governo, como qualquer um de n\u00f3s, n\u00e3o pode gastar mais do que ganha.<\/p>\n<p>N\u00e3o se trata de uma jabuticaba apenas brasileira, embora em nosso pa\u00eds o problema assuma propor\u00e7\u00f5es agudas. O novo relat\u00f3rio da ONU revela uma deteriora\u00e7\u00e3o sist\u00eamica nas condi\u00e7\u00f5es de financiamento global dos ODS. Numerosas metas n\u00e3o est\u00e3o sendo cumpridas e, o que \u00e9 mais grave, h\u00e1 retrocessos. O que se v\u00ea \u00e9 uma mistura t\u00f3xica de d\u00edvidas crescentes e insustent\u00e1veis, queda na ajuda externa e um ambiente geopol\u00edtico cada vez mais fragmentado.<\/p>\n<p>O diagn\u00f3stico \u00e9 contundente. Em 2024, o servi\u00e7o da d\u00edvida nos pa\u00edses em desenvolvimento atingiu o maior patamar em duas d\u00e9cadas. Na pr\u00e1tica, isso significa que recursos escassos, que deveriam financiar hospitais, escolas e infraestrutura verde, est\u00e3o sendo drenados para o ralo voraz de uma esp\u00e9cie de agiotagem oficial. \u00c9 uma invers\u00e3o de prioridades imposta pela soma de pol\u00edticas fiscais desequilibradas com estrat\u00e9gias monet\u00e1rias focadas apenas nos juros elevados como fator de controle inflacion\u00e1rio.<\/p>\n<p>Como se n\u00e3o bastasse, o apoio oficial aos ODS caiu 6% em 2024, para US$ 214,6 bilh\u00f5es, e deve continuar recuando. Nos pa\u00edses mais pobres, os cortes podem chegar a um quarto do total. O investimento estrangeiro direto tamb\u00e9m encolheu pelo segundo ano consecutivo. Faltam cada vez mais verbas, na propor\u00e7\u00e3o inversa do dinheiro aplicado nos servi\u00e7os das d\u00edvidas.<\/p>\n<p>Muito provavelmente, o pr\u00f3ximo relat\u00f3rio, a ser divulgado em 2027, com base em dados de 2025 e alguns de 2026, dever\u00e1 apontar o agravamento desse quadro, que j\u00e1 \u00e9 ruim, considerando o cen\u00e1rio de guerras e tens\u00f5es geopol\u00edticas crescentes. Majora\u00e7\u00e3o de taxas alfandeg\u00e1rias e impostos de importa\u00e7\u00e3o, cadeias produtivas fracionadas, conflitos b\u00e9licos e disputas comerciais acirradas t\u00eam elevado custos e reduzido oportunidades.<\/p>\n<p>O pano de fundo desse cen\u00e1rio \u00e9 a exaust\u00e3o de um modelo. A globaliza\u00e7\u00e3o, como concebida a partir dos anos de 1990, d\u00e1 sinais cada vez mais claros de esgotamento. O multilateralismo enfraquece, a coopera\u00e7\u00e3o diminui e n\u00e3o s\u00e3o cumpridos acordos recentes, como o firmado na C\u00fapula de Sevilha, em junho de 2025, para reestruturar a arquitetura financeira mundial, aliviar d\u00edvidas de pa\u00edses vulner\u00e1veis e subvencionar o progresso sustent\u00e1vel e o combate \u00e0 pobreza. Falta coordena\u00e7\u00e3o e sobra desconfian\u00e7a.<\/p>\n<p>Nesse contexto, os ODS, cujo prazo expira em 2030, parecem cada vez mais distantes. \u00c9 dif\u00edcil imaginar o cumprimento de metas t\u00e3o abrangentes, como erradica\u00e7\u00e3o da pobreza, educa\u00e7\u00e3o de qualidade, sa\u00fade universal, transi\u00e7\u00e3o energ\u00e9tica e sustentabilidade socioambiental, quando numerosas economias s\u00e3o afetadas gravemente pela d\u00edvida p\u00fablica e juros elevados e recebem cada vez menos aportes internacionais.<\/p>\n<p>O Brasil, ao carregar uma das mais corrosivas mesclas de descompasso fiscal e juros extorsivos, \u00e9 uma triste s\u00edntese desse impasse contempor\u00e2neo. Por isso, seguimos cobrando a redu\u00e7\u00e3o da Selic, que permanece exagerada, e a realiza\u00e7\u00e3o da reforma administrativa, pois precisamos de um Estado que gaste menos e entregue mais e melhores servi\u00e7os \u00e0 sociedade. N\u00e3o podemos, como se n\u00e3o houvesse amanh\u00e3, continuar gastando mais com a d\u00edvida p\u00fablica do que com a sa\u00fade, a educa\u00e7\u00e3o, a seguran\u00e7a e as pol\u00edticas voltadas \u00e0 inclus\u00e3o e ao bem-estar social.<\/p>\n<p><em><strong>*Rafael Cervone \u00e9 o presidente do Centro das Ind\u00fastrias do Estado de S\u00e3o Paulo (Ciesp) e primeiro vice-presidente da Federa\u00e7\u00e3o das Ind\u00fastrias do Estado de S\u00e3o Paulo (Fiesp).<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Rafael Cervone \u00c9 lament\u00e1vel constatar que n\u00f3s, brasileiros, estamos inclu\u00eddos entre os 3,4 bilh\u00f5es de pessoas que vivem em na\u00e7\u00f5es nas quais o dinheiro destinado ao<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":10,"featured_media":63298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[28,44],"tags":[],"class_list":["post-66847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn\" \/>\n<meta property=\"og:description\" content=\"*Rafael Cervone \u00c9 lament\u00e1vel constatar que n\u00f3s, brasileiros, estamos inclu\u00eddos entre os 3,4 bilh\u00f5es de pessoas que vivem em na\u00e7\u00f5es nas quais o dinheiro destinado ao [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/\" \/>\n<meta property=\"og:site_name\" content=\"VerdadeOn\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T20:02:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redacao VerdadeOn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacao VerdadeOn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/\",\"url\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/\",\"name\":\"Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn\",\"isPartOf\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1\",\"datePublished\":\"2026-05-11T20:02:17+00:00\",\"author\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f\"},\"breadcrumb\":{\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1\",\"width\":1170,\"height\":700,\"caption\":\"(\u00a9Jos\u00e9 Cruz\/Ag\u00eancia Brasil)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/verdadeon.com.br\/portal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como se n\u00e3o houvesse amanh\u00e3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#website\",\"url\":\"https:\/\/verdadeon.com.br\/portal\/\",\"name\":\"VerdadeOn\",\"description\":\"Not\u00edcias di\u00e1rias sobre Franca, Regi\u00e3o, Esporte, Cultura, Cotidiano, Colunas. Cobertura nos principais eventos da cidade \u00e9 aqui - Verdadeon Franca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/verdadeon.com.br\/portal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f\",\"name\":\"Redacao VerdadeOn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g\",\"caption\":\"Redacao VerdadeOn\"},\"url\":\"https:\/\/verdadeon.com.br\/portal\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/","og_locale":"pt_BR","og_type":"article","og_title":"Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn","og_description":"*Rafael Cervone \u00c9 lament\u00e1vel constatar que n\u00f3s, brasileiros, estamos inclu\u00eddos entre os 3,4 bilh\u00f5es de pessoas que vivem em na\u00e7\u00f5es nas quais o dinheiro destinado ao [\u2026]","og_url":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/","og_site_name":"VerdadeOn","article_published_time":"2026-05-11T20:02:17+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp","type":"image\/webp"}],"author":"Redacao VerdadeOn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacao VerdadeOn","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/","url":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/","name":"Como se n\u00e3o houvesse amanh\u00e3 - VerdadeOn","isPartOf":{"@id":"https:\/\/verdadeon.com.br\/portal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage"},"image":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1","datePublished":"2026-05-11T20:02:17+00:00","author":{"@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f"},"breadcrumb":{"@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#primaryimage","url":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1","contentUrl":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1","width":1170,"height":700,"caption":"(\u00a9Jos\u00e9 Cruz\/Ag\u00eancia Brasil)"},{"@type":"BreadcrumbList","@id":"https:\/\/verdadeon.com.br\/portal\/2026\/05\/11\/como-se-nao-houvesse-amanha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/verdadeon.com.br\/portal\/"},{"@type":"ListItem","position":2,"name":"Como se n\u00e3o houvesse amanh\u00e3"}]},{"@type":"WebSite","@id":"https:\/\/verdadeon.com.br\/portal\/#website","url":"https:\/\/verdadeon.com.br\/portal\/","name":"VerdadeOn","description":"Not\u00edcias di\u00e1rias sobre Franca, Regi\u00e3o, Esporte, Cultura, Cotidiano, Colunas. Cobertura nos principais eventos da cidade \u00e9 aqui - Verdadeon Franca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/verdadeon.com.br\/portal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/a5060ad1e9ea3df545188fc93ce43d2f","name":"Redacao VerdadeOn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/verdadeon.com.br\/portal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/459a9613caaaf07f582c3d0841eea68bdd66f533e465e6ba8b9cb45619572cf4?s=96&d=mm&r=g","caption":"Redacao VerdadeOn"},"url":"https:\/\/verdadeon.com.br\/portal\/author\/redacao\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/verdadeon.com.br\/portal\/wp-content\/uploads\/2026\/01\/real_moedadinheiro_jfcrz_abr_1701220043_1.webp?fit=1170%2C700&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/comments?post=66847"}],"version-history":[{"count":1,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66847\/revisions"}],"predecessor-version":[{"id":66849,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/posts\/66847\/revisions\/66849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/media\/63298"}],"wp:attachment":[{"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/media?parent=66847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/categories?post=66847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/verdadeon.com.br\/portal\/wp-json\/wp\/v2\/tags?post=66847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}